{"id":1806,"date":"2021-03-17T10:14:58","date_gmt":"2021-03-17T10:14:58","guid":{"rendered":"https:\/\/ilduomoassisi.shopagile.it\/?post_type=product&#038;p=1806"},"modified":"2021-03-17T10:16:04","modified_gmt":"2021-03-17T10:16:04","slug":"ex-voto-smaltato-7","status":"publish","type":"product","link":"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/","title":{"rendered":"Ex Voto smaltato"},"content":{"rendered":"<p>Ex voto smaltato in metallo inciso. Dipinto a mano. Dimensioni 8 x 16 cm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex voto smaltato in metallo inciso. Dipinto a mano. Dimensioni 8 x 16 cm.<\/p>\n","protected":false},"featured_media":1807,"template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ex Voto smaltato - Gallo Nero - Il Duomo di Assisi<\/title>\n<meta name=\"description\" content=\"Ex voto smaltato in metallo inciso. Dipinto a mano. Dimensioni 8 x 16 cm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex Voto smaltato - Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"og:description\" content=\"Ex voto smaltato in metallo inciso. Dipinto a mano. Dimensioni 8 x 16 cm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-17T10:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/03\/IMG_1899.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Gallo Nero\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/\",\"name\":\"Gallo Nero - Il Duomo di Assisi\",\"description\":\"Prodotti di arte sacra ad Assisi. Collezionismo scacchiere, soldatini, bastoni, clessidre, presepi, statue in legno, calici, stole, tavole dipinte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/artesacrailduomoassisi.it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/03\/IMG_1899.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/#webpage\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/\",\"name\":\"Ex Voto smaltato - Gallo Nero - Il Duomo di Assisi\",\"isPartOf\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/#primaryimage\"},\"datePublished\":\"2021-03-17T10:14:58+00:00\",\"dateModified\":\"2021-03-17T10:16:04+00:00\",\"description\":\"Ex voto smaltato in metallo inciso. Dipinto a mano. Dimensioni 8 x 16 cm.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/ex-voto-smaltato-7\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product\/1806"}],"collection":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media\/1807"}],"wp:attachment":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media?parent=1806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}