{"id":1684,"date":"2021-02-23T11:07:07","date_gmt":"2021-02-23T11:07:07","guid":{"rendered":"https:\/\/ilduomoassisi.shopagile.it\/?post_type=product&#038;p=1684"},"modified":"2021-02-23T11:08:33","modified_gmt":"2021-02-23T11:08:33","slug":"medaglia-madonna-con-bambino-oro-18-kt-2","status":"publish","type":"product","link":"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/","title":{"rendered":"Medaglia Madonna con Bambino Oro 18 Kt"},"content":{"rendered":"<p>Medaglia Madonna con Bambino in Oro 18 Kt, dipinta a mano con brillanti incastonati sulla corona. Dimensione 2 x 3 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medaglia Madonna con Bambino in Oro 18 Kt, dipinta a mano con brillanti incastonati sulla corona. Dimensione 2 x 3 cm<\/p>\n","protected":false},"featured_media":1686,"template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medaglia Madonna con Bambino Oro 18 Kt - Gallo Nero - Il Duomo di Assisi<\/title>\n<meta name=\"description\" content=\"Medaglia Madonna con Bambino in Oro 18 Kt, dipinta a mano con brillanti incastonati sulla corona. Dimensione 2 x 3 cm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medaglia Madonna con Bambino Oro 18 Kt - Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"og:description\" content=\"Medaglia Madonna con Bambino in Oro 18 Kt, dipinta a mano con brillanti incastonati sulla corona. Dimensione 2 x 3 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-23T11:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/02\/medaglia-oro-dipinta-a-mano_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Gallo Nero\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/\",\"name\":\"Gallo Nero - Il Duomo di Assisi\",\"description\":\"Prodotti di arte sacra ad Assisi. Collezionismo scacchiere, soldatini, bastoni, clessidre, presepi, statue in legno, calici, stole, tavole dipinte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/artesacrailduomoassisi.it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/02\/medaglia-oro-dipinta-a-mano_1.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/#webpage\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/\",\"name\":\"Medaglia Madonna con Bambino Oro 18 Kt - Gallo Nero - Il Duomo di Assisi\",\"isPartOf\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/#primaryimage\"},\"datePublished\":\"2021-02-23T11:07:07+00:00\",\"dateModified\":\"2021-02-23T11:08:33+00:00\",\"description\":\"Medaglia Madonna con Bambino in Oro 18 Kt, dipinta a mano con brillanti incastonati sulla corona. Dimensione 2 x 3 cm\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/medaglia-madonna-con-bambino-oro-18-kt-2\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product\/1684"}],"collection":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media\/1686"}],"wp:attachment":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media?parent=1684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}