{"id":1086,"date":"2021-02-08T11:48:20","date_gmt":"2021-02-08T11:48:20","guid":{"rendered":"https:\/\/ilduomoassisi.shopagile.it\/?post_type=product&#038;p=1086"},"modified":"2021-02-16T10:57:53","modified_gmt":"2021-02-16T10:57:53","slug":"tavola-san-francesco-santa-chiara","status":"publish","type":"product","link":"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/","title":{"rendered":"Tavola San Francesco Santa Chiara"},"content":{"rendered":"<p>Tavola in legno finemente dipinta a mano su fondo oro, riproduzione di icona bizantina raffigurante San Francesco e Santa Chiara. Pezzo unico. Dimensioni 20\u00d725 cm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tavola in legno finemente dipinta a mano su fondo oro, riproduzione di icona bizantina raffigurante San Francesco e Santa Chiara. Pezzo unico. Dimensioni 20\u00d725 cm.<\/p>\n","protected":false},"featured_media":1090,"template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tavola San Francesco Santa Chiara - Gallo Nero - Il Duomo di Assisi<\/title>\n<meta name=\"description\" content=\"Tavola in legno finemente dipinta a mano su fondo oro, riproduzione di icona bizantina raffigurante San Francesco e Santa Chiara. Pezzo unico. Dimensioni 20\u00d725 cm.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tavola San Francesco Santa Chiara - Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"og:description\" content=\"Tavola in legno finemente dipinta a mano su fondo oro, riproduzione di icona bizantina raffigurante San Francesco e Santa Chiara. Pezzo unico. Dimensioni 20\u00d725 cm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/\" \/>\n<meta property=\"og:site_name\" content=\"Gallo Nero - Il Duomo di Assisi\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T10:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/02\/IMG_1817.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Gallo Nero\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"0 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/\",\"name\":\"Gallo Nero - Il Duomo di Assisi\",\"description\":\"Prodotti di arte sacra ad Assisi. Collezionismo scacchiere, soldatini, bastoni, clessidre, presepi, statue in legno, calici, stole, tavole dipinte\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/artesacrailduomoassisi.it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/wp-content\/uploads\/2021\/02\/IMG_1817.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/#webpage\",\"url\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/\",\"name\":\"Tavola San Francesco Santa Chiara - Gallo Nero - Il Duomo di Assisi\",\"isPartOf\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/#primaryimage\"},\"datePublished\":\"2021-02-08T11:48:20+00:00\",\"dateModified\":\"2021-02-16T10:57:53+00:00\",\"description\":\"Tavola in legno finemente dipinta a mano su fondo oro, riproduzione di icona bizantina raffigurante San Francesco e Santa Chiara. Pezzo unico. Dimensioni 20\\u00d725 cm.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/artesacrailduomoassisi.it\/en\/prodotto\/tavola-san-francesco-santa-chiara\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product\/1086"}],"collection":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media\/1090"}],"wp:attachment":[{"href":"https:\/\/artesacrailduomoassisi.it\/en\/wp-json\/wp\/v2\/media?parent=1086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}